{"id":2990,"date":"2021-08-04T18:51:42","date_gmt":"2021-08-04T21:51:42","guid":{"rendered":"https:\/\/ravel.com.br\/blog\/?p=2990"},"modified":"2021-08-04T18:55:07","modified_gmt":"2021-08-04T21:55:07","slug":"por-que-acessar-sites-com-https","status":"publish","type":"post","link":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/","title":{"rendered":"Por que acessar sites com HTTPS"},"content":{"rendered":"\n<p>Todos n\u00f3s usamos a internet para pesquisas, compras, comunica\u00e7\u00e3o, atualiza\u00e7\u00e3o de not\u00edcias, entre outras in\u00fameras possibilidades. Mas estamos seguros? 100% \u00e9 praticamente imposs\u00edvel, mas principalmente <strong>quando vamos inserir alguma informa\u00e7\u00e3o dentro do site<\/strong>, \u00e9 estritamente recomend\u00e1vel que voc\u00ea olhe se o site come\u00e7a com \u201chttps\u201d. Vamos ent\u00e3o aprofundar por que acessar sites com https.<\/p>\n\n\n\n<p>Esse \u00e9 um indicativo de camadas de seguran\u00e7a para proteger as informa\u00e7\u00f5es transmitidas. Inclusive o \u201cs\u201d da sigla significa exatamente \u201c<a href=\"https:\/\/pt.wikipedia.org\/wiki\/Hyper_Text_Transfer_Protocol_Secure\">secure<\/a>\u201d (seguro). Esse protocolo foi introduzido em 1995, mas mesmo assim \u00e9 comum encontramos sites que n\u00e3o o utilizam, facilitando o vazamento de informa\u00e7\u00f5es.<\/p>\n\n\n\n<p>Quer saber mais sobre CyberSeguran\u00e7a? Veja neste artigo: &nbsp;<a href=\"https:\/\/ravel.com.br\/blog\/o-que-e-cyberseguranca\/\">O que \u00e9 CyberSeguran\u00e7a? &#8211; Blog &#8211; Ravel Tecnologia<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"323\" src=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1-1024x323.png\" alt=\"sites com HTTPS\" class=\"wp-image-2992\" srcset=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1-1024x323.png 1024w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1-300x95.png 300w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1-768x242.png 768w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1-610x192.png 610w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-1.png 1030w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Seguran\u00e7a por tr\u00e1s de sites com HTTPS<\/h2>\n\n\n\n<p>Quando um site come\u00e7a com https, significar\u00e1 que toda informa\u00e7\u00e3o que \u00e9 transmitida estar\u00e1 criptografada, onde somente voc\u00ea e o site que est\u00e1 acessando conseguir\u00e3o interpretar a mesma. Ou seja, se um cibercriminoso estiver capturando as informa\u00e7\u00f5es trafegadas (eles conseguem fazer isso atrav\u00e9s de v\u00e1rias t\u00e9cnicas, onde \u00e9 um bom tema para outro artigo. Mas tenham ci\u00eancia que n\u00e3o \u00e9 algo complexo), ele n\u00e3o conseguir\u00e1 saber o conte\u00fado transmitido.<\/p>\n\n\n\n<p>E no sentido oposto, sites com apenas http, deixam os dados expostos para serem lidos e, como consequ\u00eancia, usados para a\u00e7\u00f5es criminosas. Imagine dados de cart\u00e3o de cr\u00e9dito, senhas, entre outras informa\u00e7\u00f5es que voc\u00ea insere nos mesmos.<\/p>\n\n\n\n<p>Outro ponto relevante \u00e9 que seu equipamento pode ter alguma infec\u00e7\u00e3o onde esteja direcionando sua navega\u00e7\u00e3o para um site falso, id\u00eantico ao original. Por\u00e9m, somente o original vai ter o come\u00e7o com o \u201chttps\u201d, indicando a exist\u00eancia de um certificado digital validando a autenticidade do endere\u00e7o que voc\u00ea esteja acessando. Ou seja, voc\u00ea digitou \u201cbanco.com.br\u201d e a infec\u00e7\u00e3o do seu equipamento direcionou para <a href=\"http:\/\/banco.com.br\">http:\/\/banco.com.br<\/a> (site falso), em vez de <a href=\"https:\/\/banco.com.br\">https:\/\/banco.com.br<\/a> (site verdadeiro). E se voc\u00ea inserir seus dados no site falso, cair\u00e3o diretamente com os criminosos. Desta forma, sempre que for inserir alguma senha ou dados pessoais, verifique se est\u00e1 acessando um site com https e diminua os riscos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2-1024x469.png\" alt=\"sites com HTTPS dicas\" class=\"wp-image-2991\" srcset=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2-1024x469.png 1024w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2-300x137.png 300w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2-768x352.png 768w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2-610x279.png 610w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/https-banner-2.png 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Dicas de seguran\u00e7a<\/h2>\n\n\n\n<p>Vamos ent\u00e3o apresentar algumas dicas para o dia a dia, visando diminuir riscos e se proteger.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Repare que os navegadores j\u00e1 mostram a informa\u00e7\u00e3o \u201cN\u00e3o seguro\u201d no in\u00edcio do endere\u00e7o do site. Esse \u00e9 um indicativo de que o site n\u00e3o \u00e9 https. Desta forma, evite inserir dados nele.<\/li><li>Fique com o radar ligado mesmo com sites com https. Por exemplo, imagina que voc\u00ea est\u00e1 acessando <a href=\"https:\/\/bamco.com.br\">https:\/\/bamco.com.br<\/a> (repare que est\u00e1 com uma letra trocada, poderia tamb\u00e9m ser o \u201czero\u201d no lugar do \u201co\u201d). Esse site pode ter um certificado digital v\u00e1lido para este endere\u00e7o, sendo igual ao site <a href=\"https:\/\/banco.com.br\">https:\/\/banco.com.br<\/a> e te enganar.<\/li><li>Se o site que voc\u00ea usa tem op\u00e7\u00e3o de duplo fator de autentica\u00e7\u00e3o, ative. Pois caso seus dados de acesso digitados ser\u00e3o interceptados, n\u00e3o conseguir\u00e3o efetivar o acesso.<\/li><\/ul>\n\n\n\n<p>Aten\u00e7\u00e3o com seus h\u00e1bitos digitais. Falamos mais neste artigo: <a href=\"https:\/\/ravel.com.br\/blog\/habitos-digitais-e-seguranca\/\">H\u00e1bitos Digitais e Seguran\u00e7a &#8211; Blog &#8211; Ravel Tecnologia<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/ravel.com.br\/seguranca-da-informacao\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"133\" src=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-1024x133.png\" alt=\"\" class=\"wp-image-2306\" srcset=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-1024x133.png 1024w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-300x39.png 300w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-768x100.png 768w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-1536x199.png 1536w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-2048x266.png 2048w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-610x79.png 610w, https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/01\/CTA7-1-1080x140.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja!<\/p>\n","protected":false},"author":7,"featured_media":2993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[101,6],"tags":[],"class_list":["post-2990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-security","category-tecnologia","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por que acessar sites com HTTPS - Blog - Ravel Tecnologia<\/title>\n<meta name=\"description\" content=\"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja! - Blog Tecnologia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que acessar sites com https\" \/>\n<meta property=\"og:description\" content=\"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Tecnologia\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/raveltecnologia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T21:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T21:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nelson Corr\u00eaa Leite J\u00fanior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Por que acessar sites com https\" \/>\n<meta name=\"twitter:description\" content=\"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja!\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nelson Corr\u00eaa Leite J\u00fanior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/\",\"url\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/\",\"name\":\"Por que acessar sites com HTTPS - Blog - Ravel Tecnologia\",\"isPartOf\":{\"@id\":\"https:\/\/ravel.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg\",\"datePublished\":\"2021-08-04T21:51:42+00:00\",\"dateModified\":\"2021-08-04T21:55:07+00:00\",\"author\":{\"@id\":\"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/5809fbed911cb14566b16220749d3dcc\"},\"description\":\"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja! - Blog Tecnologia\",\"breadcrumb\":{\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage\",\"url\":\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg\",\"contentUrl\":\"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg\",\"width\":870,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ravel.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por que acessar sites com HTTPS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ravel.com.br\/blog\/#website\",\"url\":\"https:\/\/ravel.com.br\/blog\/\",\"name\":\"Blog Tecnologia\",\"description\":\"Dicas e Artigos sobre Tecnologia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ravel.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/5809fbed911cb14566b16220749d3dcc\",\"name\":\"Nelson Corr\u00eaa Leite J\u00fanior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4eeb3b5606c8a9b5aded280058cd2a1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4eeb3b5606c8a9b5aded280058cd2a1f?s=96&d=mm&r=g\",\"caption\":\"Nelson Corr\u00eaa Leite J\u00fanior\"},\"description\":\"Empres\u00e1rio desde 1997, onde \u00e9 Co-founder da Ravel Tecnologia, atuando como CEO na coordena\u00e7\u00e3o, gest\u00e3o da lideran\u00e7a e desenvolvimento estrat\u00e9gico. Especializado em Seguran\u00e7a da Informa\u00e7\u00e3o e solu\u00e7\u00f5es em nuvem. S\u00f3cio da ag\u00eancia de Marketing Digital Incandescente, com atua\u00e7\u00e3o na gest\u00e3o administrativa, financeira e estrat\u00e9gica. Busca por evoluir o uso da tecnologia aplicada aos neg\u00f3cios e as pessoas, buscando uma vis\u00e3o sist\u00eamica para fomentar e potencializar a inova\u00e7\u00e3o e crescimento. Pai de 2 lindos filhos e apreciador de uma boa cerveja.\",\"sameAs\":[\"http:\/\/ravel.com.br\",\"https:\/\/www.facebook.com\/raveltecnologia\/\",\"https:\/\/www.linkedin.com\/in\/nelson-corr\u00eaa-leite-j\u00fanior-337631160\/\"],\"url\":\"https:\/\/ravel.com.br\/blog\/author\/nelson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que acessar sites com HTTPS - Blog - Ravel Tecnologia","description":"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja! - Blog Tecnologia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/","og_locale":"pt_BR","og_type":"article","og_title":"Por que acessar sites com https","og_description":"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja!","og_url":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/","og_site_name":"Blog Tecnologia","article_author":"https:\/\/www.facebook.com\/raveltecnologia\/","article_published_time":"2021-08-04T21:51:42+00:00","article_modified_time":"2021-08-04T21:55:07+00:00","og_image":[{"width":870,"height":272,"url":"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg","type":"image\/jpeg"}],"author":"Nelson Corr\u00eaa Leite J\u00fanior","twitter_card":"summary_large_image","twitter_title":"Por que acessar sites com https","twitter_description":"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja!","twitter_misc":{"Escrito por":"Nelson Corr\u00eaa Leite J\u00fanior","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/","url":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/","name":"Por que acessar sites com HTTPS - Blog - Ravel Tecnologia","isPartOf":{"@id":"https:\/\/ravel.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage"},"image":{"@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage"},"thumbnailUrl":"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg","datePublished":"2021-08-04T21:51:42+00:00","dateModified":"2021-08-04T21:55:07+00:00","author":{"@id":"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/5809fbed911cb14566b16220749d3dcc"},"description":"Saiba neste artigo por que voc\u00ea deveria somente acessar sites que comecem com https. Se proteja! - Blog Tecnologia","breadcrumb":{"@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#primaryimage","url":"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg","contentUrl":"https:\/\/ravel.com.br\/blog\/wp-content\/uploads\/2021\/08\/Https-capa.jpg","width":870,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/ravel.com.br\/blog\/por-que-acessar-sites-com-https\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ravel.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Por que acessar sites com HTTPS"}]},{"@type":"WebSite","@id":"https:\/\/ravel.com.br\/blog\/#website","url":"https:\/\/ravel.com.br\/blog\/","name":"Blog Tecnologia","description":"Dicas e Artigos sobre Tecnologia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ravel.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/5809fbed911cb14566b16220749d3dcc","name":"Nelson Corr\u00eaa Leite J\u00fanior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ravel.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4eeb3b5606c8a9b5aded280058cd2a1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4eeb3b5606c8a9b5aded280058cd2a1f?s=96&d=mm&r=g","caption":"Nelson Corr\u00eaa Leite J\u00fanior"},"description":"Empres\u00e1rio desde 1997, onde \u00e9 Co-founder da Ravel Tecnologia, atuando como CEO na coordena\u00e7\u00e3o, gest\u00e3o da lideran\u00e7a e desenvolvimento estrat\u00e9gico. Especializado em Seguran\u00e7a da Informa\u00e7\u00e3o e solu\u00e7\u00f5es em nuvem. S\u00f3cio da ag\u00eancia de Marketing Digital Incandescente, com atua\u00e7\u00e3o na gest\u00e3o administrativa, financeira e estrat\u00e9gica. Busca por evoluir o uso da tecnologia aplicada aos neg\u00f3cios e as pessoas, buscando uma vis\u00e3o sist\u00eamica para fomentar e potencializar a inova\u00e7\u00e3o e crescimento. Pai de 2 lindos filhos e apreciador de uma boa cerveja.","sameAs":["http:\/\/ravel.com.br","https:\/\/www.facebook.com\/raveltecnologia\/","https:\/\/www.linkedin.com\/in\/nelson-corr\u00eaa-leite-j\u00fanior-337631160\/"],"url":"https:\/\/ravel.com.br\/blog\/author\/nelson\/"}]}},"_links":{"self":[{"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/posts\/2990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2990"}],"version-history":[{"count":3,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/posts\/2990\/revisions"}],"predecessor-version":[{"id":2996,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/posts\/2990\/revisions\/2996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/media\/2993"}],"wp:attachment":[{"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ravel.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}